{"id":8997,"date":"2022-08-26T07:42:17","date_gmt":"2022-08-26T07:42:17","guid":{"rendered":"https:\/\/energycasino.com\/blog\/?p=8997"},"modified":"2023-03-16T13:24:58","modified_gmt":"2023-03-16T13:24:58","slug":"ist-poker-ein-sport","status":"publish","type":"post","link":"https:\/\/energycasino.com\/blog\/de\/poker\/ist-poker-ein-sport\/","title":{"rendered":"Ist Poker ein Sport?"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_45_2 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"ez-toc-toggle-icon-1\"><label for=\"item-6a03d1962cd05\" aria-label=\"Table of Content\"><span style=\"display: flex;align-items: center;width: 35px;height: 30px;justify-content: center;direction:ltr;\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/label><input  type=\"checkbox\" id=\"item-6a03d1962cd05\"><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/energycasino.com\/blog\/de\/poker\/ist-poker-ein-sport\/#Definitionen_-_Unterschied_zwischen_Sport_und_Spiel\" title=\"Definitionen &#8211; Unterschied zwischen Sport und Spiel\">Definitionen &#8211; Unterschied zwischen Sport und Spiel<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/energycasino.com\/blog\/de\/poker\/ist-poker-ein-sport\/#Pro-_und_Kontraargumente_ob_Poker_als_Sportart_gilt\" title=\"Pro- und Kontraargumente, ob Poker als Sportart gilt\">Pro- und Kontraargumente, ob Poker als Sportart gilt<\/a><ul class='ez-toc-list-level-3'><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/energycasino.com\/blog\/de\/poker\/ist-poker-ein-sport\/#Pro\" title=\"Pro\">Pro<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/energycasino.com\/blog\/de\/poker\/ist-poker-ein-sport\/#Kontra\" title=\"Kontra\">Kontra<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/energycasino.com\/blog\/de\/poker\/ist-poker-ein-sport\/#Ist_Poker_eine_Olympische_Sportart\" title=\"Ist Poker eine Olympische Sportart?\">Ist Poker eine Olympische Sportart?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/energycasino.com\/blog\/de\/poker\/ist-poker-ein-sport\/#Warum_erkenne_einige_Leute_Poker_nicht_als_Sportart_an\" title=\"Warum erkenne einige Leute Poker nicht als Sportart an?\">Warum erkenne einige Leute Poker nicht als Sportart an?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/energycasino.com\/blog\/de\/poker\/ist-poker-ein-sport\/#Abschliesendes_Urteil\" title=\"Abschlie\u00dfendes Urteil\">Abschlie\u00dfendes Urteil<\/a><\/li><\/ul><\/nav><\/div>\n<p>Wie jeder andere Zeitvertreib bewegt sich auch das Pokern auf der Grenze zwischen &#8220;Spiel&#8221; und &#8220;Sport&#8221;. Der &#8220;Spiel&#8221;-Teil des Pokers ben\u00f6tigt wohl keiner weiteren Erkl\u00e4rung. \u00dcber den Status von Poker als &#8220;Sport&#8221; l\u00e4sst sich allerdings trefflich streiten.<\/p>\n<p>Kann Poker zu Recht als Sport betrachtet werden? Lass uns diese Frage genauer untersuchen. Beim Pokern geht es sicherlich um den Wettbewerb zwischen Einzelpersonen. Gelegentlich kommt es beim Poker auch zu Teamwettbewerben, wie z. B. beim Tag Team No-Limit Hold&#8217;em-Turnier bei den j\u00e4hrlichen World Series of Poker.<\/p>\n<p>Pokern ist zweifelsohne ein Unterhaltungsspiel. Spieler auf der ganzen Welt nehmen an diesem Spiel zu ihrem eigenen Vergn\u00fcgen teil.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Definitionen_-_Unterschied_zwischen_Sport_und_Spiel\"><\/span>Definitionen &#8211; Unterschied zwischen Sport und Spiel<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Ein Sport ist per Definition eine Aktivit\u00e4t, die Geschicklichkeit erfordert und bei der eine Person oder eine Mannschaft gegen eine andere Person oder Mannschaft antritt. Sport wird zur Unterhaltung ausge\u00fcbt und beinhaltet in der Regel ein Element der k\u00f6rperlichen Anstrengung.<\/p>\n<p>Ein Spiel ist per Definition eine wettbewerbsorientierte Aktivit\u00e4t oder ein Sport, der zum Spa\u00df betrieben wird und nach festgelegten Spielregeln gespielt wird. Diese Definition eines Spiels besagt, dass Sportarten Untergruppen von Spielen sind.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Pro-_und_Kontraargumente_ob_Poker_als_Sportart_gilt\"><\/span>Pro- und Kontraargumente, ob Poker als Sportart gilt<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Im Nachgang m\u00f6chten wir einige Punkte auff\u00fchren, warum Poker eventuell als eine Sportart gelten k\u00f6nnte und warum nicht:<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Pro\"><\/span>Pro<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>Die World Mind Sports Games halten weltbekannte Pokerturniere ab<\/li>\n<li>Gilt als Geschicklichkeitsspiel, wie z.B. das Schachspiel, und wird sogar in Ligen ausgef\u00fchrt<\/li>\n<li>Die International Federation of Poker hat das Kartenspiel als Sport anerkannt<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"Kontra\"><\/span>Kontra<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>Keine sonderliche k\u00f6rperliche Anstrengung ben\u00f6tigt<\/li>\n<li>Man muss kein Athlet sein, um Poker zu spielen<\/li>\n<li>Pokerspiel wird nach wie vor prim\u00e4r als Gl\u00fccksspiel genutzt<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Ist_Poker_eine_Olympische_Sportart\"><\/span>Ist Poker eine Olympische Sportart?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Jeder Spieler stellt sich vor, wie es w\u00e4re, wenn dieses Kartenspiel bei einem offiziellen olympischen Wettbewerb eine Medaille wert w\u00e4re, wie auch das oben angef\u00fchrte Beispiel Schach. Aber nur wenige wissen, dass es bereits viele Leute gibt, die dies \u00fcber die IFMP (International Match Poker Federation) tun.<\/p>\n<p>Derzeit bem\u00fcht sich die IFMP um die Aufnahme des Kartenspiels in die Testveranstaltung in Paris im Jahr 2024 und strebt nat\u00fcrlich die Olympischen Spiele in Los Angeles im Jahr 2028 an.<\/p>\n<p>Damit Sportarten in die Olympischen Spiele aufgenommen werden kann und einen entsprechenden Stellenwert erlangen, m\u00fcssen einige Mindestanforderungen erf\u00fcllt werden k\u00f6nnen, z. B. das Bestehen einer gemeinsamen Organisation.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Warum_erkenne_einige_Leute_Poker_nicht_als_Sportart_an\"><\/span>Warum erkenne einige Leute Poker nicht als Sportart an?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Viele Menschen fragen sich, ob es beim Pokern nicht nur um Gl\u00fcck geht, oder ob auch eine gewisse Anstrengung von N\u00f6ten ist. Diejenigen, die darauf antworten, halten an ihren \u00dcberzeugungen und Inhalte fest, ohne sich zu r\u00fchren. Wenn Du gerne an Pokerwettbewerben teilnimmst und es beleidigend findest, dass einige Leute Poker nicht als Sport betrachten (und dies auch nicht wollen), hast Du ein Recht auf diese Gef\u00fchle. Schlie\u00dflich ist es zerm\u00fcrbend, stundenlang am Tisch zu sitzen, nachzudenken, zu gr\u00fcbeln und Entscheidungen zu treffen, bei denen man viel Geld verlieren k\u00f6nnte. Aber ist es denn eine k\u00f6rperlich anstrengende Aktivit\u00e4t?<\/p>\n<p>Eine sehr gro\u00dfe Rolle, warum in den unterschiedlichsten L\u00e4ndern jenes Gl\u00fccksspiel nicht als eine Sportart angesehen wird, spielt die Tatsache, dass jeder gewinnen kann. Das ist bei keiner anderen Einzelsportart der Fall, weder kurzfristig noch sonst. Nadal schl\u00e4gt Max Mustermann immer mit einer Hand auf dem R\u00fccken, und Carlsen besiegt jeden im Schach, w\u00e4hrend er vor dem Fernseher sitzt und einen Snack zu sich nimmt.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Abschliesendes_Urteil\"><\/span>Abschlie\u00dfendes Urteil<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Seit die IMSA beschlossen hat, dass Poker eine Sportart ist, bezeichnen sich Profis, die Anerkennung in diesem Gl\u00fccksspiel suchen und es ernst nehmen, als &#8220;Pokersportler&#8221;. Diejenigen, die Online Poker lediglich damit verbinden, dass Spieler aus aller Welt mit etwas Gl\u00fcck Geld an der Teilnahme gewinnen k\u00f6nnen, scheinen damit ein Problem zu haben. Es wird angenommen, dass ein echter Sportler jemand ist, der seinen K\u00f6rper einem k\u00f6rperlichen Training unterzieht und \u00fcber dementsprechende k\u00f6rperliche F\u00e4higkeiten verf\u00fcgt. Nat\u00fcrlich k\u00f6nnen professionelle Pokerspieler auch argumentieren, dass die st\u00e4ndige Belastung ihres Gehirns tats\u00e4chlich ein k\u00f6rperliches Training ist.<\/p>\n<p>Ob ein Profi im Kartenspiel in Bezug auf die k\u00f6rperliche Anstrengung als Athlet betrachtet werden kann oder nicht, liegt nat\u00fcrlich bei Dir. Du kannst es selbst entscheiden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wie jeder andere Zeitvertreib bewegt sich auch das Pokern auf der Grenze zwischen &#8220;Spiel&#8221; und &#8220;Sport&#8221;. Der &#8220;Spiel&#8221;-Teil des Pokers ben\u00f6tigt wohl keiner weiteren Erkl\u00e4rung. \u00dcber den Status von Poker als &#8220;Sport&#8221; l\u00e4sst sich allerdings trefflich streiten. Kann Poker zu Recht als Sport betrachtet werden? Lass uns diese Frage genauer untersuchen. Beim Pokern geht es [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[109],"tags":[],"class_list":["post-8997","post","type-post","status-publish","format-standard","hentry","category-poker"],"acf":[],"_links":{"self":[{"href":"https:\/\/energycasino.com\/blog\/de\/wp-json\/wp\/v2\/posts\/8997"}],"collection":[{"href":"https:\/\/energycasino.com\/blog\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/energycasino.com\/blog\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/energycasino.com\/blog\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/energycasino.com\/blog\/de\/wp-json\/wp\/v2\/comments?post=8997"}],"version-history":[{"count":0,"href":"https:\/\/energycasino.com\/blog\/de\/wp-json\/wp\/v2\/posts\/8997\/revisions"}],"wp:attachment":[{"href":"https:\/\/energycasino.com\/blog\/de\/wp-json\/wp\/v2\/media?parent=8997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/energycasino.com\/blog\/de\/wp-json\/wp\/v2\/categories?post=8997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/energycasino.com\/blog\/de\/wp-json\/wp\/v2\/tags?post=8997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}